<br />
<b>Deprecated</b>:  Using ${var} in strings is deprecated, use {$var} instead in <b>/nas/content/live/dcelebirds/wp-content/plugins/sitepress-multilingual-cms/classes/API/REST/class-wpml-ate-proxy.php</b> on line <b>128</b><br />
{"id":13633,"date":"2014-11-21T17:09:30","date_gmt":"2014-11-21T22:09:30","guid":{"rendered":"http:\/\/celebrateurbanbirds.org\/?post_type=event&#038;p=13633"},"modified":"2014-12-06T12:05:26","modified_gmt":"2014-12-06T17:05:26","slug":"club-de-green-jay-mayan-birding","status":"publish","type":"event","link":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/","title":{"rendered":"Club de Green Jay Mayan Birding"},"content":{"rendered":"<p>La historia de c\u00f3mo el club de Green Jay Mayan Birding comenz\u00f3 es una muy linda. Los fundadores del club, una pareja encantadora, vieron pasar unas aves de colores brillantes maravillosos fuera de su casa, que se encuentra en la Pen\u00ednsula de Yucat\u00e1n, M\u00e9xico. La belleza de estas aves los cautiv\u00f3, y no pudieron quedarse tranquilos preguntarse, \u00bfc\u00f3mo se llamar\u00e1n esas aves tan bellas? Lo primero que hicieron fue buscar las aves en el internet y dar una visita a la librer\u00eda local, donde compraron su primera gu\u00eda de aves, con la esperanza de poder encontrar la respuesta que buscaban. <figure class=\"right medium\"><img decoding=\"async\" src=\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/Chara-Verde-1-300x225.jpg\" srcset=\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/Chara-Verde-1-300x225.jpg 300w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/Chara-Verde-1-1024x768.jpg 1024w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/Chara-Verde-1-346x259.jpg 346w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/Chara-Verde-1-500x375.jpg 500w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/Chara-Verde-1-400x300.jpg 400w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/Chara-Verde-1-120x90.jpg 120w\" sizes=\"(max-width: 767px) 100vw, (max-width: 991px) 96vw, (max-width: 1920px) 67vw, 1024px\" alt=\"\" \/><figcaption><span class=\"copyright\">(Photo &copy; Courtesy of Green Jay Mayan Birding)<\/span><\/figcaption><\/figure>\u00bfSu respuesta? <a href=\"http:\/\/www.allaboutbirds.org\/guide\/green_jay\/id\" target=\"_blank\">Charas Verdes<\/a>. Su curiosidad pronto se convirti\u00f3 en pasi\u00f3n mientras continuaron observando, descubriendo y fotografiando aves en la Pen\u00ednsula de Yucat\u00e1n. Su pasi\u00f3n por las aves era contagiosa, y gracias a su inter\u00e9s y dedicaci\u00f3n, naci\u00f3 el club de Green Jay Mayan Birding para toda la comunidad. Lo fundaron con el objetivo de promover la cultura de la observaci\u00f3n de aves, entre personas de todas las edades y de distintas historias de vida. <\/p>\n<p>El club de Green Jay Mayan Birding ha tenido un gran impacto en la comunidad de la pen\u00ednsula, al promover por una parte el aprecio y la conservaci\u00f3n de las aves, y por otra parte, promover el ecoturismo en la pen\u00ednsula en torno a la observaci\u00f3n de aves. Por esto mismo, el club est\u00e1 teniendo un impacto en la sociedad y la econom\u00eda local. Miembros del club incluyen amas de casa, doctores, fot\u00f3grafos, estudiantes, miembros de la comunidad Maya, ancianos y la lista contin\u00faa. Uno de los grandes logros del club es que ha logrado unir a la diversidad de personas que componen la cultura local de la pen\u00ednsula de Yucat\u00e1n. Todos con una meta com\u00fan- el observar y ayudar a las aves silvestres. Las actividades del club tambi\u00e9n han generado recursos econ\u00f3micos que ayudan a muchos. Cuando un grupo se va de excursi\u00f3n, el club apoya a los negocios locales, se hospeda con gente u hoteles del \u00e1rea, compra comida local y otros adem\u00e1s de usar los servicios y apoyar las actividades culturales locales.<\/p>\n<p><figure class=\"left medium\"><img decoding=\"async\" src=\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/IMG_9570-300x225.jpg\" srcset=\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/IMG_9570-300x225.jpg 300w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/IMG_9570-1024x768.jpg 1024w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/IMG_9570-346x259.jpg 346w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/IMG_9570-500x375.jpg 500w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/IMG_9570-400x300.jpg 400w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/IMG_9570-120x90.jpg 120w\" sizes=\"(max-width: 767px) 100vw, (max-width: 991px) 96vw, (max-width: 1920px) 67vw, 1024px\" alt=\"\" \/><figcaption><span class=\"copyright\">(Photo &copy; Courtesy of Green Jay Mayan Birding)<\/span><\/figcaption><\/figure>Otra forma de promover la observaci\u00f3n de aves es a trav\u00e9s de exposiciones fotogr\u00e1ficas; la \u00faltima se llama &#8220;Volando por la Pen\u00ednsula&#8221; en un caf\u00e9 que se encarga de promover a los artistas locales. La due\u00f1a del caf\u00e9 es miembro del club, y es un ejemplo de la variedad de personas que participa en el avistamiento de aves con el club. Por medio de la exposici\u00f3n, el club de Green Jay Mayan Birding es capaz de cautivar a quienes visitan el caf\u00e9; generando inter\u00e9s y curiosidad por las aves de la pen\u00ednsula. <\/p>\n<p>La influencia que el club de Green Jay Mayan Birding ha tenido en la comunidad pajarera de la pen\u00ednsula ha sido incre\u00edble, promoviendo la educaci\u00f3n ambiental y la conservaci\u00f3n.  Cuando el club reci\u00e9n comenz\u00f3 en el a\u00f1o 2012, hab\u00edan s\u00f3lo dos organizaciones de observadores de aves en la regi\u00f3n. Este n\u00famero ha crecido tanto desde entonces, que ahora hay 17 clubes de observadores de aves en la pen\u00ednsula con los mismos objetivos que el club de Green Jay Mayan Birding. Desde que el club de Green Jay Mayan Birding fue fundado, la cantidad de mexicanos reportando aves en la Pen\u00ednsula de Yucat\u00e1n ha aumentado en un 10%. <figure class=\"right medium\"><img decoding=\"async\" src=\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/12\/IMG_6268-300x199.jpg\" srcset=\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/12\/IMG_6268-300x199.jpg 300w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/12\/IMG_6268-1024x681.jpg 1024w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/12\/IMG_6268-346x230.jpg 346w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/12\/IMG_6268-500x333.jpg 500w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/12\/IMG_6268-450x300.jpg 450w, https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/12\/IMG_6268-135x90.jpg 135w\" sizes=\"(max-width: 767px) 100vw, (max-width: 991px) 96vw, (max-width: 1920px) 67vw, 1024px\" alt=\"\" \/><figcaption><span class=\"copyright\">(Photo &copy; Courtesy of Green Jay Mayan Birding)<\/span><\/figcaption><\/figure>Este aumento en el n\u00famero de observadores es relevante porque se acumula m\u00e1s informaci\u00f3n sobre las especies de aves locales, y se crea conciencia ambiental. Adem\u00e1s, por su puesto, de que se creen m\u00e1s clubes como el de Green Jay Mayan Birding en otras comunidades. Al crear conciencia acerca de la gran diversidad de aves que existen en sus propias ciudades y pueblos, el club de Green Jay Mayan Birding tiene la oportunidad de ense\u00f1arle a la comunidad sobre la importancia de mantener los h\u00e1bitats de estas aves y su importancia en la ecolog\u00eda tanto local como global.  Ahora que los efectos del cambio clim\u00e1tico y la degradaci\u00f3n del medio ambiente son tan evidentes, se hace imperativo el querer descubrir y hacer m\u00e1s por la naturaleza local y sus especies, promover y ayudar a la creaci\u00f3n y mantenci\u00f3n de h\u00e1bitats que ayuden a las aves y otros seres vivientes. El club de Green Jay Mayan Birding es un gran ejemplo de c\u00f3mo todos podemos ayudar a nuestras comunidades y al planeta. <\/p>\n<p>Si deseas saber m\u00e1s acerca de las actividades del club de Green Jay Mayan Birding, puedes visitar su <a href=\"https:\/\/es-es.facebook.com\/pages\/Green-Jay-Mayan-Birding\/328557430592469\" target=\"_blank\">p\u00e1gina de Facebook<\/a>.<\/p>\n<p><br \/>\nFotos cortes\u00eda del club de Green Jay Mayan Birding.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La historia de c\u00f3mo el club de Green Jay Mayan Birding comenz\u00f3 es una muy linda. Los fundadores del club, una pareja encantadora, vieron pasar unas aves de colores brillantes maravillosos fuera de su casa, que se encuentra en la Pen\u00ednsula de Yucat\u00e1n, M\u00e9xico. La belleza de estas aves los cautiv\u00f3, y no pudieron quedarse tranquilos preguntarse, \u00bfc\u00f3mo se llamar\u00e1n esas aves tan bellas? Lo primero que hicieron fue buscar las aves en el internet y dar una visita a la librer\u00eda local, donde compraron su primera gu\u00eda de aves, con la esperanza de poder encontrar la respuesta que buscaban....<\/p>\n","protected":false},"featured_media":13621,"template":"","tags":[],"years":[6498],"event_types":[7127],"class_list":["post-13633","event","type-event","status-publish","has-post-thumbnail","hentry","years-2014-es","event_types-partner-highlights-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Club de Green Jay Mayan Birding | Celebrate Urban Birds<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Club de Green Jay Mayan Birding | Celebrate Urban Birds\" \/>\n<meta property=\"og:description\" content=\"La historia de c\u00f3mo el club de Green Jay Mayan Birding comenz\u00f3 es una muy linda. Los fundadores del club, una pareja encantadora, vieron pasar unas aves de colores brillantes maravillosos fuera de su casa, que se encuentra en la Pen\u00ednsula de Yucat\u00e1n, M\u00e9xico. La belleza de estas aves los cautiv\u00f3, y no pudieron quedarse tranquilos preguntarse, \u00bfc\u00f3mo se llamar\u00e1n esas aves tan bellas? Lo primero que hicieron fue buscar las aves en el internet y dar una visita a la librer\u00eda local, donde compraron su primera gu\u00eda de aves, con la esperanza de poder encontrar la respuesta que buscaban....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/\" \/>\n<meta property=\"og:site_name\" content=\"Celebrate Urban Birds\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CelebrateBirds\/\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-06T17:05:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/green-jay2-e1416340175764.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2971\" \/>\n\t<meta property=\"og:image:height\" content=\"2093\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@celebratebirds\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/\",\"url\":\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/\",\"name\":\"Club de Green Jay Mayan Birding | Celebrate Urban Birds\",\"isPartOf\":{\"@id\":\"https:\/\/test.celebrateurbanbirds.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/green-jay2-e1416340175764.jpg\",\"datePublished\":\"2014-11-21T22:09:30+00:00\",\"dateModified\":\"2014-12-06T17:05:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#primaryimage\",\"url\":\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/green-jay2-e1416340175764.jpg\",\"contentUrl\":\"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/green-jay2-e1416340175764.jpg\",\"width\":2971,\"height\":2093},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/test.celebrateurbanbirds.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Club de Green Jay Mayan Birding\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test.celebrateurbanbirds.org\/#website\",\"url\":\"https:\/\/test.celebrateurbanbirds.org\/\",\"name\":\"Celebrate Urban Birds\",\"description\":\"We&#039;re All Close To Birds!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test.celebrateurbanbirds.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Club de Green Jay Mayan Birding | Celebrate Urban Birds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/","og_locale":"es_ES","og_type":"article","og_title":"Club de Green Jay Mayan Birding | Celebrate Urban Birds","og_description":"La historia de c\u00f3mo el club de Green Jay Mayan Birding comenz\u00f3 es una muy linda. Los fundadores del club, una pareja encantadora, vieron pasar unas aves de colores brillantes maravillosos fuera de su casa, que se encuentra en la Pen\u00ednsula de Yucat\u00e1n, M\u00e9xico. La belleza de estas aves los cautiv\u00f3, y no pudieron quedarse tranquilos preguntarse, \u00bfc\u00f3mo se llamar\u00e1n esas aves tan bellas? Lo primero que hicieron fue buscar las aves en el internet y dar una visita a la librer\u00eda local, donde compraron su primera gu\u00eda de aves, con la esperanza de poder encontrar la respuesta que buscaban....","og_url":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/","og_site_name":"Celebrate Urban Birds","article_publisher":"https:\/\/www.facebook.com\/CelebrateBirds\/","article_modified_time":"2014-12-06T17:05:26+00:00","og_image":[{"width":2971,"height":2093,"url":"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/green-jay2-e1416340175764.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@celebratebirds","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/","url":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/","name":"Club de Green Jay Mayan Birding | Celebrate Urban Birds","isPartOf":{"@id":"https:\/\/test.celebrateurbanbirds.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#primaryimage"},"image":{"@id":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#primaryimage"},"thumbnailUrl":"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/green-jay2-e1416340175764.jpg","datePublished":"2014-11-21T22:09:30+00:00","dateModified":"2014-12-06T17:05:26+00:00","breadcrumb":{"@id":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#primaryimage","url":"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/green-jay2-e1416340175764.jpg","contentUrl":"https:\/\/test.celebrateurbanbirds.org\/wp-content\/uploads\/2014\/11\/green-jay2-e1416340175764.jpg","width":2971,"height":2093},{"@type":"BreadcrumbList","@id":"https:\/\/test.celebrateurbanbirds.org\/es\/community\/events\/club-de-green-jay-mayan-birding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.celebrateurbanbirds.org\/"},{"@type":"ListItem","position":2,"name":"Club de Green Jay Mayan Birding"}]},{"@type":"WebSite","@id":"https:\/\/test.celebrateurbanbirds.org\/#website","url":"https:\/\/test.celebrateurbanbirds.org\/","name":"Celebrate Urban Birds","description":"We&#039;re All Close To Birds!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.celebrateurbanbirds.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"feature_on_homepage":[],"_links":{"self":[{"href":"https:\/\/test.celebrateurbanbirds.org\/es\/wp-json\/wp\/v2\/event\/13633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.celebrateurbanbirds.org\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/test.celebrateurbanbirds.org\/es\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.celebrateurbanbirds.org\/es\/wp-json\/wp\/v2\/media\/13621"}],"wp:attachment":[{"href":"https:\/\/test.celebrateurbanbirds.org\/es\/wp-json\/wp\/v2\/media?parent=13633"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test.celebrateurbanbirds.org\/es\/wp-json\/wp\/v2\/tags?post=13633"},{"taxonomy":"years","embeddable":true,"href":"https:\/\/test.celebrateurbanbirds.org\/es\/wp-json\/wp\/v2\/years?post=13633"},{"taxonomy":"event_types","embeddable":true,"href":"https:\/\/test.celebrateurbanbirds.org\/es\/wp-json\/wp\/v2\/event_types?post=13633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}